{"id":170727,"date":"2026-06-04T08:39:55","date_gmt":"2026-06-04T08:39:55","guid":{"rendered":"https:\/\/bas-ip.com\/integrations-entranceiq\/"},"modified":"2026-06-12T10:06:08","modified_gmt":"2026-06-12T10:06:08","slug":"integrations-entranceiq","status":"publish","type":"page","link":"https:\/\/bas-ip.com\/fr\/integrations-entranceiq\/","title":{"rendered":"EntranceIQ"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"141\" src=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2026\/06\/EntranceIQ_logo_n-300x141.png\" alt=\"\" class=\"wp-image-167923\" srcset=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2026\/06\/EntranceIQ_logo_n-300x141.png 300w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2026\/06\/EntranceIQ_logo_n-768x360.png 768w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2026\/06\/EntranceIQ_logo_n-767x360.png 767w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2026\/06\/EntranceIQ_logo_n.png 802w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n<h3 data-path-to-node=\"0\">\u00c0 propos du partenaire<\/h3>\n<p data-path-to-node=\"1\">EntranceIQ fournit des logiciels modernes de contr\u00f4le d&rsquo;acc\u00e8s et de gestion des visiteurs, con\u00e7us pour les r\u00e9sidences ferm\u00e9es, les syndicats de copropri\u00e9t\u00e9 et les domaines priv\u00e9s. La plateforme combine un acc\u00e8s intuitif pour les r\u00e9sidents, des flux de travail de s\u00e9curit\u00e9 robustes et des int\u00e9grations flexibles pour am\u00e9liorer la s\u00e9curit\u00e9, l&rsquo;efficacit\u00e9 et l&rsquo;exp\u00e9rience utilisateur. Avec des composants tels qu&rsquo;EIQ-Connect, EIQ-Secure et l&rsquo;acc\u00e8s invit\u00e9 par QR code, EntranceIQ permet aux communaut\u00e9s d&rsquo;automatiser les proc\u00e9dures d&rsquo;entr\u00e9e tout en r\u00e9duisant les frais op\u00e9rationnels et en am\u00e9liorant la fiabilit\u00e9.<\/p>\n<h3 data-path-to-node=\"3\">Aper\u00e7u de l&rsquo;int\u00e9gration<\/h3>\n<p data-path-to-node=\"4\">Notre partenaire a mis en \u0153uvre une int\u00e9gration personnalis\u00e9e entre la platine interphone <strong>BAS-IP AA-14FBIS<\/strong> et la <strong>plateforme EntranceIQ<\/strong>, offrant ainsi une exp\u00e9rience de contr\u00f4le d&rsquo;acc\u00e8s unifi\u00e9e et intelligente tirant parti \u00e0 la fois de la communication SIP et de la connectivit\u00e9 API.<\/p>\n<h3 data-path-to-node=\"6\">Fonctionnalit\u00e9s cl\u00e9s d\u00e9livr\u00e9es<\/h3>\n<ul>\n<li data-path-to-node=\"7,0,0\"><b data-path-to-node=\"7,0,0\" data-index-in-node=\"0\">Routage des appels vid\u00e9o<\/b> vers le service de garde virtuel (Virtual Guard) d&rsquo;EntranceIQ.<\/li>\n<li data-path-to-node=\"7,1,0\"><b data-path-to-node=\"7,1,0\" data-index-in-node=\"0\">Flux vid\u00e9o RTSP en direct<\/b> pour une surveillance de la situation.<\/li>\n<li data-path-to-node=\"7,2,0\"><b data-path-to-node=\"7,2,0\" data-index-in-node=\"0\">Authentification par QR code<\/b> via l&rsquo;API de l&rsquo;interphone.<\/li>\n<\/ul>\n<h3 data-path-to-node=\"8\">Principaux avantages :<\/h3>\n<ul>\n<li data-path-to-node=\"9,0,0\">Prise en charge d&rsquo;une gestion avanc\u00e9e des visiteurs \u00e0 distance sans n\u00e9cessiter de mat\u00e9riel personnalis\u00e9 complexe.<\/li>\n<li data-path-to-node=\"9,1,0\">Activation de flux de travail op\u00e9rateurs complets avec vid\u00e9o en direct et contr\u00f4le interactif des portes.<\/li>\n<li data-path-to-node=\"9,2,0\">Modernisation de l&rsquo;acc\u00e8s aux communaut\u00e9s et aux installations gr\u00e2ce \u00e0 une entr\u00e9e autonome par QR code.<\/li>\n<li data-path-to-node=\"9,3,0\">D\u00e9veloppement sur l&rsquo;infrastructure existante du partenaire en utilisant des standards ouverts.<\/li>\n<\/ul>\n\n<!-- START Block Sign Up --><section id=\"block_629678229e935\" class=\"sign-up-section\">\r\n\r\n    <div class=\"form-holder js-form\" data-aos=\"fade-right\">\r\n                    <div class=\"title-block h3\">Sign up for connection<\/div>\r\n        \r\n                    <div class=\"text-block\">\r\n                Filling out all the information needed to answer you as quickly as possible            <\/div>\r\n        \r\n                    \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f157874-o1\" lang=\"fr-FR\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/170727#wpcf7-f157874-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"157874\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f157874-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"row\"> \n <label><span class=\"label-text\">Nom<\/span> \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"text-full-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom\" value=\"\" type=\"text\" name=\"text-full-name\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"> \n <label><span class=\"label-text\">T\u00e9l\u00e9phone*<\/span> \n<span class=\"wpcf7-form-control-wrap\" data-name=\"phonetext-270\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-phonetext\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"T\u00e9l\u00e9phone*\" value=\"\" type=\"text\" name=\"phonetext-270\" \/><input type=\"hidden\" name=\"phonetext-270-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"> \n <label><span class=\"label-text\">E-mail<\/span> \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"email-e-mail\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"email-e-mail\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"><span>Votre pays<\/span> \n <label><span class=\"wpcf7-form-control-wrap\" data-name=\"countrytext-126\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-countrytext wpcf7-text wpcf7-validates-as-countrytext\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"countrytext-126\" \/><\/span><\/label>\n<\/div> \n<div class=\"row\"> \n <button type=\"submit\" class=\"btn\">Envoyer<\/button> \n<\/div> \n<div class=\"row\"> \n <span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-931\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"Int\u00e9grateur\" \/><span class=\"wpcf7-list-item-label\">Int\u00e9grateur<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"Constructeur\" \/><span class=\"wpcf7-list-item-label\">Constructeur<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"Utilisateur final\" \/><span class=\"wpcf7-list-item-label\">Utilisateur final<\/span><\/label><\/span><\/span><\/span> \n<\/div> \n<div class=\"row row-upload-file\"> \n <label class=\"upload-file-block js-upload-file\">Joindre un fichier \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"file-466\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"file-466\" \/><\/span><\/label> \n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\r\n\r\n\t\t    <div class=\"text-holder\" data-aos=\"fade-left\">\r\n\t\t\t\t\t\t    <h3 class=\"title-block\">How Can We Help?<\/h3>\r\n\t\t\t\r\n\t\t\t                <div class=\"text-block\">\r\n                    Please select a topic below related to your inquiry. If you don&rsquo;t find what you need, fill out our contact form.                <\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t    <ul class=\"link-list\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Get Inspired<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/features\/\">\r\n\t\t\t\t\t\t\t\t        Discover what&rsquo;s beneath our intercom\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Become a Partner<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/distributors\/\">\r\n\t\t\t\t\t\t\t\t        Expand your business with BAS-IP intercom\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Check the Guides<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/support\/\">\r\n\t\t\t\t\t\t\t\t        Download detailed manuals and schemes\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\r\n\t\t\t\t\t\t    <h3 class=\"title-block\">Our contacts<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<ul class=\"contact-list\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<strong>Sales:<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"mailto:sa&#108;es&#64;b&#97;s&#45;i&#112;.co&#109;\">s&#97;l&#101;s&#64;b&#97;&#115;&#45;i&#112;.co&#109;<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<strong>Technical support:<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"mailto:&#115;&#117;pp&#111;rt&#64;&#98;&#97;s&#45;i&#112;&#46;&#99;om\">su&#112;&#112;or&#116;&#64;&#98;a&#115;&#45;&#105;p.c&#111;m<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<\/div>\r\n\t<\/section>\r\n\r\n\r\n\r\n<!-- END Block Sign Up -->","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos du partenaire EntranceIQ fournit des logiciels modernes de contr\u00f4le d&rsquo;acc\u00e8s et de gestion des visiteurs, con\u00e7us pour les r\u00e9sidences ferm\u00e9es, les syndicats de copropri\u00e9t\u00e9 et les domaines priv\u00e9s. La plateforme combine un acc\u00e8s intuitif pour les r\u00e9sidents, des flux de travail de s\u00e9curit\u00e9 robustes et des int\u00e9grations flexibles pour am\u00e9liorer la s\u00e9curit\u00e9, l&rsquo;efficacit\u00e9 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-custom-breadcrumbs.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-170727","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/pages\/170727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/comments?post=170727"}],"version-history":[{"count":2,"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/pages\/170727\/revisions"}],"predecessor-version":[{"id":170791,"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/pages\/170727\/revisions\/170791"}],"wp:attachment":[{"href":"https:\/\/bas-ip.com\/fr\/wp-json\/wp\/v2\/media?parent=170727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}