{"id":122912,"date":"2023-03-24T09:51:10","date_gmt":"2023-03-24T09:51:10","guid":{"rendered":"https:\/\/bas-ip.com\/?page_id=122912"},"modified":"2024-11-22T13:54:17","modified_gmt":"2024-11-22T13:54:17","slug":"axxonsoft","status":"publish","type":"page","link":"https:\/\/bas-ip.com\/es\/axxonsoft\/","title":{"rendered":"AxxonSoft"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"219\" src=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/AxxonSoft.png\" alt=\"\" class=\"wp-image-63599\" srcset=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/AxxonSoft.png 682w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/AxxonSoft-300x96.png 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/div>\n\n<!-- START Block Integrations Text & Image --><section id=\"block_641d7ab5f70cf\" class=\"integrations-text-image-section\">\r\n\t\t<div class=\"image-holder\" data-aos=\"fade-left\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-1024x576.jpg 1024w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-300x169.jpg 300w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-768x432.jpg 768w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-1536x864.jpg 1536w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-767x431.jpg 767w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2-1534x863.jpg 1534w,  https:\/\/bas-ip.com\/wp-content\/uploads\/2023\/03\/p_img_s_p2.jpg 1833w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\t<\/div>\r\n\t\r\n\t<div class=\"text-holder\" data-aos=\"fade-right\">\r\n\t\t\t\t\t\t<div class=\"text-block\">\r\n\t\t\t<h1>Combinaci\u00f3n de seguridad e innovaci\u00f3n: los interfonos BAS-IP y AxxonSoft<\/h1>\n<p>Imag\u00ednese esto: una integraci\u00f3n perfecta de la tecnolog\u00eda de comunicaci\u00f3n m\u00e1s avanzada con el software de seguridad m\u00e1s avanzado. Eso es precisamente lo que hemos logrado con la innovadora colaboraci\u00f3n entre BAS-IP, los pioneros de las soluciones avanzadas de interfon\u00eda, y AxxonSoft, la vanguardia del software de gesti\u00f3n de v\u00eddeo y gesti\u00f3n de informaci\u00f3n de seguridad f\u00edsica.<\/p>\n<p>Para obtener informaci\u00f3n m\u00e1s detallada, visite nuestro <a href=\"https:\/\/basip.atlassian.net\/wiki\/spaces\/Integrations\/pages\/5046901\/Integration+with+Axxonsoft+Intelect+software\" target=\"_blank\" rel=\"noopener\"><strong>WIKI<\/strong><\/a>.<\/p>\n<h2><strong>Experimente el futuro del control de accesos y la seguridad<\/strong><\/h2>\n<p>Se acabaron los d\u00edas en los que hab\u00eda que depender de sistemas dispares para la comunicaci\u00f3n y la vigilancia. Al combinar los interfonos BAS-IP con el software de primer nivel de AxxonSoft, hemos creado la soluci\u00f3n de seguridad definitiva, que le garantiza un control de acceso y una supervisi\u00f3n visual sin precedentes. \u00bfEl resultado? Un entorno m\u00e1s seguro, inteligente y eficiente para su propiedad residencial, comercial o industrial.<\/p>\n<h2><strong>Libere el poder de la integraci\u00f3n de \u00faltima generaci\u00f3n<\/strong><\/h2>\n<p>La sinergia entre estos dos l\u00edderes del sector desbloquea una serie de funciones que transformar\u00e1n su juego de seguridad:<\/p>\n<h3><strong>V\u00eddeo en tiempo real<\/strong><\/h3>\n<p>Mantenga vigilada su propiedad con la transmisi\u00f3n de v\u00eddeo de gran nitidez de los interfonos BAS-IP, integrados a la perfecci\u00f3n con la plataforma de gesti\u00f3n de v\u00eddeo de AxxonSoft.<\/p>\n<h3><strong>Control de acceso avanzado<\/strong><\/h3>\n<p>Mejore su estrategia de control de accesos con funciones avanzadas de reconocimiento facial y escaneado de documentos de identidad, para que las entradas no autorizadas sean cosa del pasado.<\/p>\n<h3><strong>Gesti\u00f3n remota<\/strong><\/h3>\n<p>Gestione todo su sistema de seguridad de forma remota desde una ubicaci\u00f3n centralizada, utilizando la intuitiva interfaz de usuario y las potentes herramientas de gesti\u00f3n de AxxonSoft.<\/p>\n<h3><strong>Sistema unificado<\/strong><\/h3>\n<p>Una plataforma para gobernarlos a todos Disfrute de una experiencia optimizada con un ecosistema de seguridad totalmente integrado, que reduce la complejidad y garantiza un rendimiento \u00f3ptimo.<\/p>\t\t<\/div>\r\n\t\t\r\n\t\t\r\n\t\t\t<\/div>\r\n<\/section>\r\n<!-- END Block Integrations Text & Image -->\n\n<!-- START Block Sign Up --><section id=\"block_629678229e935\" class=\"sign-up-section\">\r\n\r\n    <div class=\"form-holder js-form\" data-aos=\"fade-right\">\r\n                    <div class=\"title-block h3\">Sign up for connection<\/div>\r\n        \r\n                    <div class=\"text-block\">\r\n                Filling out all the information needed to answer you as quickly as possible            <\/div>\r\n        \r\n                    \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f102-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/122912#wpcf7-f102-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"102\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f102-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"row\"> \n <label><span class=\"label-text\">Name<\/span> \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"text-full-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"text-full-name\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"> \n <label><span class=\"label-text\">Phone*<\/span> \n<span class=\"wpcf7-form-control-wrap\" data-name=\"phonetext-270\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-phonetext\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone*\" value=\"\" type=\"text\" name=\"phonetext-270\" \/><input type=\"hidden\" name=\"phonetext-270-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"> \n <label><span class=\"label-text\">E-mail<\/span> \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"email-e-mail\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"email-e-mail\" \/><\/span><\/label> \n<\/div> \n<div class=\"row\"><span>Your country<\/span> \n <label><span class=\"wpcf7-form-control-wrap\" data-name=\"countrytext-126\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-countrytext wpcf7-text wpcf7-validates-as-countrytext\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"countrytext-126\" \/><\/span> <\/label>\n<\/div> \n<div class=\"row\"> \n <button type=\"submit\" class=\"btn\">Send<\/button> \n<\/div> \n<div class=\"row\"> \n <span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-931\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"Integrator\" \/><span class=\"wpcf7-list-item-label\">Integrator<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"Builder\" \/><span class=\"wpcf7-list-item-label\">Builder<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"checkbox-931[]\" value=\"End-User\" \/><span class=\"wpcf7-list-item-label\">End-User<\/span><\/label><\/span><\/span><\/span> \n<\/div> \n<div class=\"row row-upload-file\"> \n <label class=\"upload-file-block js-upload-file\">Attach file \n  <span class=\"wpcf7-form-control-wrap\" data-name=\"file-466\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"file-466\" \/><\/span><\/label> \n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\r\n\r\n\t\t    <div class=\"text-holder\" data-aos=\"fade-left\">\r\n\t\t\t\t\t\t    <h3 class=\"title-block\">How Can We Help?<\/h3>\r\n\t\t\t\r\n\t\t\t                <div class=\"text-block\">\r\n                    Please select a topic below related to your inquiry. If you don&#8217;t find what you need, fill out our contact form.                <\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t    <ul class=\"link-list\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Get Inspired<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/features\/\">\r\n\t\t\t\t\t\t\t\t        Discover what&#8217;s beneath our intercom\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Become a Partner<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/distributors\/\">\r\n\t\t\t\t\t\t\t\t        Expand your business with BAS-IP intercom\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <strong>Check the Guides<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"\/support\/\">\r\n\t\t\t\t\t\t\t\t        Download detailed manuals and schemes\t\t\t\t\t\t\t\t    <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\r\n\t\t\t\t\t\t    <h3 class=\"title-block\">Our contacts<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<ul class=\"contact-list\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<strong>Sales:<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"mailto:sal&#101;s&#64;&#98;&#97;&#115;&#45;&#105;p&#46;c&#111;&#109;\">sa&#108;&#101;s&#64;&#98;&#97;&#115;-&#105;p.&#99;o&#109;<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<strong>Technical support:<\/strong>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <a href=\"mailto:&#115;&#117;&#112;&#112;&#111;rt&#64;&#98;as&#45;i&#112;.c&#111;m\">s&#117;&#112;&#112;o&#114;&#116;&#64;&#98;a&#115;&#45;i&#112;.&#99;om<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<\/div>\r\n\t<\/section>\r\n\r\n\r\n\r\n<!-- END Block Sign Up -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-custom-breadcrumbs.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-122912","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/pages\/122912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/comments?post=122912"}],"version-history":[{"count":2,"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/pages\/122912\/revisions"}],"predecessor-version":[{"id":122914,"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/pages\/122912\/revisions\/122914"}],"wp:attachment":[{"href":"https:\/\/bas-ip.com\/es\/wp-json\/wp\/v2\/media?parent=122912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}